{"id":1598,"date":"2020-10-29T09:26:08","date_gmt":"2020-10-29T09:26:08","guid":{"rendered":"http:\/\/sgh-service.com\/?p=1598"},"modified":"2022-09-01T09:12:37","modified_gmt":"2022-09-01T09:12:37","slug":"p2p-automatisierung","status":"publish","type":"post","link":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/","title":{"rendered":"Die Vorteile von Purchase to Pay (P2P) Automatisierung"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\r\n<p>Da die Covid-19-Pandemie eine weltweite Wirtschaftsrezession ausl\u00f6st, war der Druck auf die Finanzchefs noch nie so gro\u00df wie heute, Kosten- und Zeiteinsparungen voranzutreiben. W\u00e4hrend sich Gesch\u00e4ftsmodelle, Budgets und Prozesse w\u00e4hrend der Wachstumsphasen st\u00e4ndig weiterentwickeln, werden sie nun vollst\u00e4ndig auf die lange Bank geschoben, da die Finanzleiter erkennen, dass sie agil und kreativ sein m\u00fcssen, um ihre Unternehmen durch diese Covid-19-Pandemie zu navigieren.<\/p>\r\n<p>Dar\u00fcber hinaus hat sich die Rolle eines CFO von einer Verwaltungsfunktion zu einer strategischen Funktion entwickelt, bei der die CEOs nicht nur Transparenz in allen Aspekten der Finanzprozesse fordern, sondern auch Empfehlungen auf der Grundlage von umsetzbaren Erkenntnissen und Daten erhalten m\u00f6chten. Hier wenden sich Finanzleiter an die Purchase-to-Pay (P2P)-L\u00f6sungen von SGH, um ihre Finanzprozesse digital zu transformieren und zu automatisieren und so folgende Vorteile zu erzielen:<\/p>\r\n<p><strong>Massive Kostensenkungen<\/strong><\/p>\r\n<p>Die P2P-L\u00f6sungen von SGH bieten jedem CFO ein besseres Gef\u00fchl daf\u00fcr, wie das Unternehmen sein Geld ausgibt. Dadurch k\u00f6nnen Finanzleiter bessere Preise aushandeln, Einzelg\u00e4nger-K\u00e4ufe stoppen und verhindern, dass Lieferanten zu hohe Preise verlangen.\u00a0 Diese F\u00e4higkeit, aus 100% der Finanzdaten aussagekr\u00e4ftige Einblicke zu gewinnen, bietet spannende M\u00f6glichkeiten f\u00fcr Kosteneinsparungen und Wachstum!<\/p>\r\n<p><strong>Verbesserte Mitarbeiterproduktivit\u00e4t<\/strong><\/p>\r\n<p>Die P2P-L\u00f6sungen von SGH automatisieren den Prozess des Kaufens und Bezahlens von Waren und Dienstleistungen, wodurch eine Reihe manueller Aufgaben, einschlie\u00dflich der m\u00fchsamen und zeitraubenden Eingabe von Lieferantenrechnungsdaten, wegfallen. Dadurch erh\u00e4lt das Unternehmen mehr Arbeitsstunden zur\u00fcck, so dass sich die Mitarbeiter auf strategische Aktivit\u00e4ten mit hoher Hebelwirkung konzentrieren k\u00f6nnen, die sich positiv auf das Endergebnis des Unternehmens auswirken.<\/p>\r\n<p><strong>Sichtbarkeit und Transparenz<\/strong><\/p>\r\n<p>CFOs haben oft sehr wenig Einblick in ihre Finanzverwaltungsprozesse. Viele haben keine Ahnung, wo sich eine bestimmte Lieferantenrechnung zu einem bestimmten Zeitpunkt befindet oder ob eine Bestellung \u00fcberhaupt erf\u00fcllt wurde und eingegangen ist, was es schwierig macht, rechtzeitig R\u00fcckstellungen zu bilden oder Anfragen zeitnah zu l\u00f6sen. Mit den P2P-L\u00f6sungen von SGH kann ein Finanzleiter den gesamten P2P-Prozess auf einem System mit einer einzigen Schnittstelle verwalten, w\u00e4hrend die Entscheidungstr\u00e4ger Zugriff auf finanzielle Trends und die Fortschritte der Abteilung bei der Erreichung ihrer Ziele haben.<\/p>\r\n<p><strong>Risiko menschlichen Versagens eliminiert<\/strong><\/p>\r\n<p>Zus\u00e4tzlich zu den offensichtlichen Kosten- und Zeiteinsparungen bedeutet die Digitalisierung und Automatisierung des P2P-Prozesses mit SGH, dass das Risiko menschlichen Versagens eliminiert wird. Beispiele f\u00fcr menschliches Versagen ohne die P2P-L\u00f6sungen von SGH, die verheerende Auswirkungen auf ein Unternehmen haben k\u00f6nnen, sind doppelte Rechnungsstellung, die Zahlung eines falschen Betrags, die Zahlung der Rechnung an einen falschen Lieferanten oder die Zahlung einer betr\u00fcgerischen Rechnung.<\/p>\r\n<p>Bereits vor der Covid-19-Pandemie identifizierten viele Unternehmen digitale Technologie und Automatisierung als eine M\u00f6glichkeit, die betriebliche Effizienz, die Kundenerfahrung und die Innovationsf\u00e4higkeit zu verbessern. Heute ist die Notwendigkeit, digitale Technologie und Automatisierung einzuf\u00fchren, so gro\u00df wie nie zuvor. CFOs, in ihren neu entwickelten strategischen Rollen, sollten Technologien wie die P2P-L\u00f6sungen von SGH nutzen, da sie sonst Gefahr laufen, von der Konkurrenz abgeh\u00e4ngt zu werden.<\/p>\r\n<p><strong>\u00dcber die SGH Gruppe<\/strong><\/p>\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p>Die SGH-Gruppe ist ein global operierender Spezialist f\u00fcr Supply-Chain-L\u00f6sungen. 1990 gegr\u00fcndet befindet sich das Unternehmen in der 3. Generation im Familienbesitz. An den Standorten in Hildesheim, Hannover, Ho-Chi-Minh-Stadt und Singapur besch\u00e4ftigt die SGH-Gruppe insgesamt \u00fcber 220 Mitarbeiter. Diese betreuen weltweit Projekte in \u00fcber 50 L\u00e4ndern. Insgesamt werden in den Multi-Channel-Plattforml\u00f6sungen der SGH-Gruppe \u00fcber 30 Mio. Belege verarbeitet. \u00dcber 15.000 Kunden \u2013 von KMU bis hin zu internationalen Konzernen \u2013 setzen weltweit auf die L\u00f6sungen der SGH Gruppe.<\/p>\r\n<p><a href=\"https:\/\/www.sgh-net.de\/\">sgh-net.de<\/a><\/p>\r\n<\/blockquote>\r\n<p>\u00a0<\/p>\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Da die Covid-19-Pandemie eine weltweite Wirtschaftsrezession ausl\u00f6st, war der Druck auf die Finanzchefs noch<span class=\"read_more_area\"><a class=\"read-more\" href=\"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/\"> Continue Reading <\/a><\/span><\/p>\n","protected":false},"author":27,"featured_media":2118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Vorteile von Purchase to Pay (P2P) Automatisierung - SGH Service<\/title>\n<meta name=\"description\" content=\"Die P2P-L\u00f6sungen von SGH bieten jedem CFO ein besseres Gef\u00fchl daf\u00fcr, wie das Unternehmen sein Geld ausgibt. Dadurch k\u00f6nnen Finanzleiter bessere Preise aushandeln, Einzelg\u00e4nger-K\u00e4ufe stoppen und verhindern, dass Lieferanten zu hohe Preise verlangen. Diese F\u00e4higkeit, aus 100% der Finanzdaten aussagekr\u00e4ftige Einblicke zu gewinnen, bietet spannende M\u00f6glichkeiten f\u00fcr Kosteneinsparungen und Wachstum!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Vorteile von Purchase to Pay (P2P) Automatisierung - SGH Service\" \/>\n<meta property=\"og:description\" content=\"Die P2P-L\u00f6sungen von SGH bieten jedem CFO ein besseres Gef\u00fchl daf\u00fcr, wie das Unternehmen sein Geld ausgibt. Dadurch k\u00f6nnen Finanzleiter bessere Preise aushandeln, Einzelg\u00e4nger-K\u00e4ufe stoppen und verhindern, dass Lieferanten zu hohe Preise verlangen. Diese F\u00e4higkeit, aus 100% der Finanzdaten aussagekr\u00e4ftige Einblicke zu gewinnen, bietet spannende M\u00f6glichkeiten f\u00fcr Kosteneinsparungen und Wachstum!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/\" \/>\n<meta property=\"og:site_name\" content=\"SGH Service\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-29T09:26:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-01T09:12:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sgh-service.com\/wp-content\/uploads\/2021\/05\/pexels-fauxels-3184465-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luise B\u00e4umer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luise B\u00e4umer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/\"},\"author\":{\"name\":\"Luise B\u00e4umer\",\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/#\\\/schema\\\/person\\\/c15b08216565bd335d1ae35143b02c39\"},\"headline\":\"Die Vorteile von Purchase to Pay (P2P) Automatisierung\",\"datePublished\":\"2020-10-29T09:26:08+00:00\",\"dateModified\":\"2022-09-01T09:12:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/\"},\"wordCount\":617,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgh-service.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/pexels-fauxels-3184465-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/\",\"url\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/\",\"name\":\"Die Vorteile von Purchase to Pay (P2P) Automatisierung - SGH Service\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sgh-service.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/pexels-fauxels-3184465-scaled.jpg\",\"datePublished\":\"2020-10-29T09:26:08+00:00\",\"dateModified\":\"2022-09-01T09:12:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/#\\\/schema\\\/person\\\/c15b08216565bd335d1ae35143b02c39\"},\"description\":\"Die P2P-L\u00f6sungen von SGH bieten jedem CFO ein besseres Gef\u00fchl daf\u00fcr, wie das Unternehmen sein Geld ausgibt. Dadurch k\u00f6nnen Finanzleiter bessere Preise aushandeln, Einzelg\u00e4nger-K\u00e4ufe stoppen und verhindern, dass Lieferanten zu hohe Preise verlangen. Diese F\u00e4higkeit, aus 100% der Finanzdaten aussagekr\u00e4ftige Einblicke zu gewinnen, bietet spannende M\u00f6glichkeiten f\u00fcr Kosteneinsparungen und Wachstum!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sgh-service.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/pexels-fauxels-3184465-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/sgh-service.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/pexels-fauxels-3184465-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Accounting Services\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/p2p-automatisierung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Vorteile von Purchase to Pay (P2P) Automatisierung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/\",\"name\":\"SGH Service\",\"description\":\"Financial Supply Chain L\u00f6sungen und Zentralregulierung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/#\\\/schema\\\/person\\\/c15b08216565bd335d1ae35143b02c39\",\"name\":\"Luise B\u00e4umer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f20eb0dec0626d3ec6aeff50a1183b6c0ba4b348ad07d9b7812f5db5fb637cb7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f20eb0dec0626d3ec6aeff50a1183b6c0ba4b348ad07d9b7812f5db5fb637cb7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f20eb0dec0626d3ec6aeff50a1183b6c0ba4b348ad07d9b7812f5db5fb637cb7?s=96&d=mm&r=g\",\"caption\":\"Luise B\u00e4umer\"},\"url\":\"https:\\\/\\\/sgh-service.com\\\/en\\\/author\\\/lbaeumer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Vorteile von Purchase to Pay (P2P) Automatisierung - SGH Service","description":"Die P2P-L\u00f6sungen von SGH bieten jedem CFO ein besseres Gef\u00fchl daf\u00fcr, wie das Unternehmen sein Geld ausgibt. Dadurch k\u00f6nnen Finanzleiter bessere Preise aushandeln, Einzelg\u00e4nger-K\u00e4ufe stoppen und verhindern, dass Lieferanten zu hohe Preise verlangen. Diese F\u00e4higkeit, aus 100% der Finanzdaten aussagekr\u00e4ftige Einblicke zu gewinnen, bietet spannende M\u00f6glichkeiten f\u00fcr Kosteneinsparungen und Wachstum!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/","og_locale":"en_US","og_type":"article","og_title":"Die Vorteile von Purchase to Pay (P2P) Automatisierung - SGH Service","og_description":"Die P2P-L\u00f6sungen von SGH bieten jedem CFO ein besseres Gef\u00fchl daf\u00fcr, wie das Unternehmen sein Geld ausgibt. Dadurch k\u00f6nnen Finanzleiter bessere Preise aushandeln, Einzelg\u00e4nger-K\u00e4ufe stoppen und verhindern, dass Lieferanten zu hohe Preise verlangen. Diese F\u00e4higkeit, aus 100% der Finanzdaten aussagekr\u00e4ftige Einblicke zu gewinnen, bietet spannende M\u00f6glichkeiten f\u00fcr Kosteneinsparungen und Wachstum!","og_url":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/","og_site_name":"SGH Service","article_published_time":"2020-10-29T09:26:08+00:00","article_modified_time":"2022-09-01T09:12:37+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/sgh-service.com\/wp-content\/uploads\/2021\/05\/pexels-fauxels-3184465-scaled.jpg","type":"image\/jpeg"}],"author":"Luise B\u00e4umer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Luise B\u00e4umer","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/#article","isPartOf":{"@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/"},"author":{"name":"Luise B\u00e4umer","@id":"https:\/\/sgh-service.com\/en\/#\/schema\/person\/c15b08216565bd335d1ae35143b02c39"},"headline":"Die Vorteile von Purchase to Pay (P2P) Automatisierung","datePublished":"2020-10-29T09:26:08+00:00","dateModified":"2022-09-01T09:12:37+00:00","mainEntityOfPage":{"@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/"},"wordCount":617,"commentCount":0,"image":{"@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/#primaryimage"},"thumbnailUrl":"https:\/\/sgh-service.com\/wp-content\/uploads\/2021\/05\/pexels-fauxels-3184465-scaled.jpg","articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sgh-service.com\/en\/p2p-automatisierung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/","url":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/","name":"Die Vorteile von Purchase to Pay (P2P) Automatisierung - SGH Service","isPartOf":{"@id":"https:\/\/sgh-service.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/#primaryimage"},"image":{"@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/#primaryimage"},"thumbnailUrl":"https:\/\/sgh-service.com\/wp-content\/uploads\/2021\/05\/pexels-fauxels-3184465-scaled.jpg","datePublished":"2020-10-29T09:26:08+00:00","dateModified":"2022-09-01T09:12:37+00:00","author":{"@id":"https:\/\/sgh-service.com\/en\/#\/schema\/person\/c15b08216565bd335d1ae35143b02c39"},"description":"Die P2P-L\u00f6sungen von SGH bieten jedem CFO ein besseres Gef\u00fchl daf\u00fcr, wie das Unternehmen sein Geld ausgibt. Dadurch k\u00f6nnen Finanzleiter bessere Preise aushandeln, Einzelg\u00e4nger-K\u00e4ufe stoppen und verhindern, dass Lieferanten zu hohe Preise verlangen. Diese F\u00e4higkeit, aus 100% der Finanzdaten aussagekr\u00e4ftige Einblicke zu gewinnen, bietet spannende M\u00f6glichkeiten f\u00fcr Kosteneinsparungen und Wachstum!","breadcrumb":{"@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sgh-service.com\/en\/p2p-automatisierung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/#primaryimage","url":"https:\/\/sgh-service.com\/wp-content\/uploads\/2021\/05\/pexels-fauxels-3184465-scaled.jpg","contentUrl":"https:\/\/sgh-service.com\/wp-content\/uploads\/2021\/05\/pexels-fauxels-3184465-scaled.jpg","width":2560,"height":1707,"caption":"Accounting Services"},{"@type":"BreadcrumbList","@id":"https:\/\/sgh-service.com\/en\/p2p-automatisierung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sgh-service.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Die Vorteile von Purchase to Pay (P2P) Automatisierung"}]},{"@type":"WebSite","@id":"https:\/\/sgh-service.com\/en\/#website","url":"https:\/\/sgh-service.com\/en\/","name":"SGH Service","description":"Financial Supply Chain L\u00f6sungen und Zentralregulierung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sgh-service.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sgh-service.com\/en\/#\/schema\/person\/c15b08216565bd335d1ae35143b02c39","name":"Luise B\u00e4umer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f20eb0dec0626d3ec6aeff50a1183b6c0ba4b348ad07d9b7812f5db5fb637cb7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f20eb0dec0626d3ec6aeff50a1183b6c0ba4b348ad07d9b7812f5db5fb637cb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f20eb0dec0626d3ec6aeff50a1183b6c0ba4b348ad07d9b7812f5db5fb637cb7?s=96&d=mm&r=g","caption":"Luise B\u00e4umer"},"url":"https:\/\/sgh-service.com\/en\/author\/lbaeumer\/"}]}},"_links":{"self":[{"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/posts\/1598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/comments?post=1598"}],"version-history":[{"count":0,"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/posts\/1598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/media\/2118"}],"wp:attachment":[{"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/media?parent=1598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/categories?post=1598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgh-service.com\/en\/wp-json\/wp\/v2\/tags?post=1598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}